{"id":1916,"date":"2012-06-15T13:18:10","date_gmt":"2012-06-15T13:18:10","guid":{"rendered":"http:\/\/www.marcobani.it\/blog\/2012\/06\/15\/pisa-luminara-2012-la-vera-notte-magica\/"},"modified":"2012-06-15T13:18:10","modified_gmt":"2012-06-15T13:18:10","slug":"pisa-luminara-2012-la-vera-notte-magica","status":"publish","type":"post","link":"https:\/\/www.marcobani.it\/blog\/2012\/06\/15\/pisa-luminara-2012-la-vera-notte-magica\/","title":{"rendered":"#Pisa Luminara 2012, la vera notte magica"},"content":{"rendered":"<p>Durante gli Europei e i Mondiali di calcio mi viene sempre in mente la favolosa canzone di Gianna Nannini e Edoardo Bennato &#8220;notti magiche&#8221;, anche se quest&#8217;anno molto probabilmente non ci sar\u00e0 nulla di fantastico. Ma per i pisani la &#8216;notte magica&#8217; \u00e8 un&#8217;altra. Purtroppo un impegno in Inghilterra mi tiene lontano dalla Luminara di quest&#8217;anno, ed \u00e8 la prima volta. Infatti ero sempre riuscito a incastrare lavoro e studio, regalandomi sempre la possibilit\u00e0 di vivere quella che considero la festa della citt\u00e0. Ed \u00e8 incredibile che, nonostante tutto, il fatto di non esserci  mi dispiace molto. D&#8217;altra parte ogni edizione della nostra notte bianca vede delle novit\u00e0 e delle sorprese, che siano un banchetto di cibo locale o una band che suona, girare per Pisa scoprendo le molte iniziative \u00e8 uno dei piaceri pi\u00f9 entusiasmanti che la citt\u00e0 offre durante l\u2019anno.<br \/>\nPi\u00f9 di centoventimila lumini (per un totale di 12.5 Km di biancheria, di cui 2 km di biancheria nuova, record assoluto) vestiranno Pisa di un\u2019aura magica, quasi sacrale, per una delle notti pi\u00f9 belle dell\u2019anno. Pisa si mette il suo vestito migliore ed \u00e8 pronta ancora una volta a vedere i suoi lungarni stracolmi di gente, pisani e non.<br \/>\nE l&#8217;edizione 2012 sar\u00e0 magnifica, cercando di riproporre gli ottimi spunti degli anni passati e aggiungendone di altri: 130 palazzi illuminati, (pi\u00f9 del 95%),  8 piattaforme mobili che spareranno i fuochi d&#8217;artificio in modo da essere visti da tutti sui Lungarni, nessuna interferenza visiva (luci artificiali), la Torre ricoperta di lumini, giochi di luce e proiezioni 3D (come abbiamo visto per il Capodanno pisano), 16 bagni chimici dislocati in citt\u00e0 che si spera possano contenere i &#8220;risultati&#8221; dell&#8217;euforia collettiva. E tante altre piccole novit\u00e0.<br \/>\nInoltre quest&#8217;anno l&#8217;edizione sar\u00e0 di Sabato, con il conseguente aumento delle persone previste (pi\u00f9 di 100mila, pi\u00f9 di tutti gli stessi abitanti del Comune).<br \/>\nCi sono tutti gli ingredienti per innamorarvi ( chi per la prima volta, chi recidivo) di quella che \u00e8 la manifestazione storica pi\u00f9 seguita della Toscana.<br \/>\nStiamo ancora spettando una risposta da parte dell&#8217;UNESCO per l&#8217;inserimento della Luminara nell&#8217;elenco dei beni immateriali dell&#8217;umanit\u00e0. Dovrebbe arrivare entro il 2013 quando a Pisa tra marzo e aprile del 2013 si terr\u00e0 il decennale della Convenzione Unesco per i Beni dell&#8217;Umanit\u00e0.<br \/>\nFacciamo vedere al mondo che questo riconoscimento ci spetta: armatevi del vostro sorriso migliore, scendete per strada, perdonate le immancabili mancanze e, soprattutto, godetevi la serata.<br \/>\nDurante la Luminara c&#8217;\u00e8 pi\u00f9 gusto ad essere pisani. Fatemi rimpiangere di non essere l\u00ec a godermi un&#8217;altra  serata magica ( <a href=\"http:\/\/www.pisainformaflash.it\/notizie\/dettaglio.html?nId=10725\">e non dimenticatevi di leggere le istruzioni per l&#8217;uso su mobilit\u00e0 e sicurezza messe a disposizione dall&#8217;amministrazione per evitare il caos<\/a>).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante gli Europei e i Mondiali di calcio mi viene sempre in mente la favolosa canzone di Gianna Nannini e Edoardo Bennato &#8220;notti magiche&#8221;, anche se quest&#8217;anno molto probabilmente non ci sar\u00e0 nulla di fantastico. Ma per i pisani la &#8216;notte magica&#8217; \u00e8 un&#8217;altra. Purtroppo un impegno in Inghilterra mi tiene lontano dalla Luminara di [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/www.marcobani.it\/blog\/wp-json\/wp\/v2\/posts\/1916"}],"collection":[{"href":"https:\/\/www.marcobani.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.marcobani.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.marcobani.it\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.marcobani.it\/blog\/wp-json\/wp\/v2\/comments?post=1916"}],"version-history":[{"count":0,"href":"https:\/\/www.marcobani.it\/blog\/wp-json\/wp\/v2\/posts\/1916\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.marcobani.it\/blog\/wp-json\/wp\/v2\/media?parent=1916"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.marcobani.it\/blog\/wp-json\/wp\/v2\/categories?post=1916"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.marcobani.it\/blog\/wp-json\/wp\/v2\/tags?post=1916"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}